{"id":34648,"date":"2022-04-28T12:44:47","date_gmt":"2022-04-28T10:44:47","guid":{"rendered":"https:\/\/www.arte-d.it\/?page_id=34648"},"modified":"2022-04-29T09:31:03","modified_gmt":"2022-04-29T07:31:03","slug":"home-new-04-22","status":"publish","type":"page","link":"https:\/\/www.arte-d.it\/it\/","title":{"rendered":"HOME New (04.22)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-home-new-04-22.php","meta":{"content-type":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"HOME - Arte &amp; D s.r.l. Seating solution Nonostante la presenza ben radicata nel mercato globale, siamo ancora spinti dalla voglia di crescere, assieme ai nostri partners di lavoro, ed a continuare a fornire non solo sedute per ufficio ma anche le migliori condizioni lavorative possibili.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arte-d.it\/it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HOME - Arte &amp; D s.r.l. Seating solution\" \/>\n<meta property=\"og:description\" content=\"HOME - Arte &amp; D s.r.l. Seating solution Nonostante la presenza ben radicata nel mercato globale, siamo ancora spinti dalla voglia di crescere, assieme ai nostri partners di lavoro, ed a continuare a fornire non solo sedute per ufficio ma anche le migliori condizioni lavorative possibili.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arte-d.it\/it\/\" \/>\n<meta property=\"og:site_name\" content=\"Arte &amp; D s.r.l. Seating solution\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-29T07:31:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arte-d.it\/#organization\",\"name\":\"ARTE & D SRL\",\"url\":\"https:\/\/www.arte-d.it\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/arteanddsrl\/?hl=it\",\"https:\/\/www.linkedin.com\/company\/68194373\/admin\/\",\"https:\/\/www.youtube.com\/channel\/UC96EcLaAiNxv7zZ8WPAlFWw\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.arte-d.it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.arte-d.it\/wp-content\/uploads\/2022\/01\/Logo-arte_d-032-rosso_PNG.png\",\"contentUrl\":\"https:\/\/www.arte-d.it\/wp-content\/uploads\/2022\/01\/Logo-arte_d-032-rosso_PNG.png\",\"width\":701,\"height\":301,\"caption\":\"ARTE & D SRL\"},\"image\":{\"@id\":\"https:\/\/www.arte-d.it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arte-d.it\/#website\",\"url\":\"https:\/\/www.arte-d.it\/\",\"name\":\"Arte & D s.r.l. Seating solution\",\"description\":\"seating solutions for office and contract, office chairs, armchairs for office, design chairs,\",\"publisher\":{\"@id\":\"https:\/\/www.arte-d.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.arte-d.it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arte-d.it\/it\/#webpage\",\"url\":\"https:\/\/www.arte-d.it\/it\/\",\"name\":\"HOME - Arte &amp; D s.r.l. Seating solution\",\"isPartOf\":{\"@id\":\"https:\/\/www.arte-d.it\/#website\"},\"datePublished\":\"2022-04-28T10:44:47+00:00\",\"dateModified\":\"2022-04-29T07:31:03+00:00\",\"description\":\"HOME - Arte & D s.r.l. Seating solution Nonostante la presenza ben radicata nel mercato globale, siamo ancora spinti dalla voglia di crescere, assieme ai nostri partners di lavoro, ed a continuare a fornire non solo sedute per ufficio ma anche le migliori condizioni lavorative possibili.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arte-d.it\/it\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arte-d.it\/it\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arte-d.it\/it\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arte-d.it\/it\/\",\"url\":\"https:\/\/www.arte-d.it\/it\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.arte-d.it\/it\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.arte-d.it\/it\/wp-json\/wp\/v2\/pages\/34648"}],"collection":[{"href":"https:\/\/www.arte-d.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.arte-d.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.arte-d.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arte-d.it\/it\/wp-json\/wp\/v2\/comments?post=34648"}],"version-history":[{"count":7,"href":"https:\/\/www.arte-d.it\/it\/wp-json\/wp\/v2\/pages\/34648\/revisions"}],"predecessor-version":[{"id":34691,"href":"https:\/\/www.arte-d.it\/it\/wp-json\/wp\/v2\/pages\/34648\/revisions\/34691"}],"wp:attachment":[{"href":"https:\/\/www.arte-d.it\/it\/wp-json\/wp\/v2\/media?parent=34648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}